{"id":72878,"date":"2023-09-26T10:00:46","date_gmt":"2023-09-26T16:00:46","guid":{"rendered":"https:\/\/askthescientists.com\/?p=72878"},"modified":"2023-10-17T10:18:11","modified_gmt":"2023-10-17T16:18:11","slug":"ceramides","status":"publish","type":"post","link":"https:\/\/askthescientists.com\/es\/ceramides\/","title":{"rendered":"Todo sobre las ceramidas"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter wp-image-72866 size-full\" src=\"https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953.jpeg\" alt=\"\" width=\"835\" height=\"509\" srcset=\"https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953.jpeg 835w, https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953-400x244.jpeg 400w, https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953-768x468.jpeg 768w, https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953-705x430.jpeg 705w\" sizes=\"(max-width: 835px) 100vw, 835px\" \/>La piel, el \u00f3rgano m\u00e1s grande del cuerpo, es la primera l\u00ednea de defensa contra las toxinas y las amenazas externas, y tambi\u00e9n es lo primero que ve la gente, por eso la cuidamos, para tener el mejor aspecto posible. Por suerte, la funci\u00f3n y el aspecto de la piel est\u00e1n relacionados.<\/p>\n<p>La piel seca y agrietada es m\u00e1s vulnerable a los efectos medioambientales. Por otro lado, una piel tersa e hidratada funciona como debe, impidiendo la entrada de irritantes y reteniendo la humedad.<\/p>\n<p>Posiblemente no hayas o\u00eddo hablar de las ceramidas, pero son uno de los componentes m\u00e1s importantes de tu piel. Son maestras en proteger y ayudar a retener la humedad. Recientemente, las ceramidas se han convertido incluso en un ingrediente clave de muchos productos para el cuidado de la piel. Estas cremas y humectantes refuerzan los niveles naturales de ceramidas para ayudar a mantener la salud de la piel.<\/p>\n<h2>\u00bfQu\u00e9 son las ceramidas?<\/h2>\n<p>Las ceramidas son l\u00edpidos que representan aproximadamente el 50% de la composici\u00f3n de la piel y desempe\u00f1an un papel primordial en la funci\u00f3n y el aspecto de la barrera cut\u00e1nea. El resto de la piel est\u00e1 formado por capas de c\u00e9lulas que siguen un proceso constante de muerte y renovaci\u00f3n con <a href=\"https:\/\/askthescientists.com\/skin-cells\/\">c\u00e9lulas nuevas<\/a>. Es probable que est\u00e9s familiarizado con las capas cut\u00e1neas que corresponden a la epidermis y a la dermis, pero quiz\u00e1 te sorprenda saber que estas capas de c\u00e9lulas estrechamente empaquetadas dependen de un &#8220;sello&#8221; bioqu\u00edmico para que la piel funcione correctamente. Por ello, las ceramidas son tan importantes para la epidermis como las propias c\u00e9lulas cut\u00e1neas. Piensa en las ceramidas como el pegamento que mantiene unidas las c\u00e9lulas de la piel para formar una barrera funcional. Cuanto m\u00e1s saludable est\u00e9 esa barrera, m\u00e1s protege, manteniendo incluso la piel mejor hidratada.<\/p>\n<p>Aplicadas por v\u00eda t\u00f3pica, las ceramidas favorecen los niveles de humectaci\u00f3n y mantienen saludable la barrera cut\u00e1nea. Las ceramidas pueden ser sint\u00e9ticas (artificiales) o naturales, como las que se encuentran en las capas externas de la piel. Para entender realmente lo que son, analic\u00e9moslas desde el punto de vista de la bioqu\u00edmica, pero no te preocupes, ser\u00e1 f\u00e1cil y r\u00e1pido.<\/p>\n<p>Todas las ceramidas est\u00e1n formadas por un compuesto llamado esfingosina, una cadena de \u00e1tomos de carbono con un amino\u00e1cido unido a ella. Cuando la esfingosina se une a otros \u00e1cidos grasos, forma ceramidas. Existen 12 tipos distintos de ceramidas, denominadas ceramida 1-12, seg\u00fan el tipo de esfingosina que sea y el tipo de \u00e1cido graso que se una a ella.<\/p>\n<h2>\u00bfPor qu\u00e9 son importantes las ceramidas?<\/h2>\n<p>Pueden surgir problemas cut\u00e1neos si las ceramidas no funcionan correctamente. La edad y el da\u00f1o solar pueden reducir la eficacia de tus ceramidas naturales. Con el tiempo, a medida que se agotan los niveles de ceramida, una barrera cut\u00e1nea debilitada puede dar lugar a una piel m\u00e1s seca y problem\u00e1tica. La m\u00e9trica que los cient\u00edficos cosm\u00e9ticos utilizan para medir la hidrataci\u00f3n de la piel se denomina &#8220;p\u00e9rdida transepid\u00e9rmica de agua&#8221;. La piel seca o irritada presenta una mayor p\u00e9rdida transepid\u00e9rmica de agua y una menor capacidad de retenci\u00f3n de agua.<\/p>\n<p>Los productos para el cuidado de la piel ricos en ceramidas ayudan a mantener y equilibrar la piel, y reducen la p\u00e9rdida transepid\u00e9rmica de agua, incluso despu\u00e9s de que los niveles de ceramidas hayan disminuido.<\/p>\n<p>Los beneficios que ofrecen las ceramidas a la piel en t\u00e9rminos de nutrici\u00f3n pueden:<\/p>\n<ul>\n<li>Fortalecer la barrera protectora de la piel<\/li>\n<li>Ayudar a tu piel a retener la humedad<\/li>\n<li>Rejuvenecer el aspecto de tu piel<\/li>\n<li>Aportar un aspecto de mayor densidad y tersura a la piel, con menos arrugas y l\u00edneas de expresi\u00f3n visibles<\/li>\n<\/ul>\n<h2>Productos a base de ceramidas adecuados para ti<\/h2>\n<p>Un envase adecuado mantiene el m\u00e1ximo rendimiento de los productos formulados a base de ceramidas. Cuando busques productos de calidad a base de ceramidas, evita los tarros de vidrio o los envases transparentes. Muchos de los ingredientes &#8220;antienvejecimiento&#8221; m\u00e1s populares para el cuidado de la piel son sensibles a la oxidaci\u00f3n y pueden perder su eficacia cuando se exponen a la luz y al aire. Por lo tanto, busca tubos o frascos opacos con bombas y dispensadores herm\u00e9ticos.<\/p>\n<p>Si un producto contiene ceramidas, aparecer\u00e1n en la lista de ingredientes. Busca tambi\u00e9n ingredientes relacionados con las ceramidas, como la fitoesfingosina y la esfingosina. Todos ellos favorecen la producci\u00f3n natural de ceramidas de la piel cuando se aplican por v\u00eda t\u00f3pica. Y puede ser incluso m\u00e1s f\u00e1cil pues debido a que ofrecen beneficios tan codiciados, muchos productos muestran estos ingredientes en la parte delantera y central del envase.<\/p>\n<p>Las ceramidas son beneficiosas para todo tipo de pieles, incluso las sensibles, porque son un componente natural de la epidermis. Si deseas actualizar tu rutina de cuidado de la piel o todav\u00eda eres principiante en el mundo del cuidado de la piel, prueba un producto con ceramidas y experimenta los beneficios de una piel hidratada y de aspecto saludable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La piel, el \u00f3rgano m\u00e1s grande del cuerpo, es la primera l\u00ednea de defensa contra las toxinas y las amenazas externas, y tambi\u00e9n es lo primero que ve la gente, por eso la cuidamos, para tener el mejor aspecto posible. Por suerte, la funci\u00f3n y el aspecto de la piel est\u00e1n relacionados. La piel seca [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":72873,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[286],"tags":[20776],"class_list":["post-72878","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nutrition_spotlight-es","tag-skin-care-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Todo sobre las ceramidas - Ask The Scientists<\/title>\n<meta name=\"description\" content=\"Conoce uno de los componentes m\u00e1s importantes de la barrera natural de la piel que adem\u00e1s es un ingrediente clave en muchos productos para el cuidado de la piel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/askthescientists.com\/es\/ceramides\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Todo sobre las ceramidas - Ask The Scientists\" \/>\n<meta property=\"og:description\" content=\"Conoce uno de los componentes m\u00e1s importantes de la barrera natural de la piel que adem\u00e1s es un ingrediente clave en muchos productos para el cuidado de la piel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/askthescientists.com\/es\/ceramides\/\" \/>\n<meta property=\"og:site_name\" content=\"Ask The Scientists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AskTheScientists\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-26T16:00:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-17T16:18:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"835\" \/>\n\t<meta property=\"og:image:height\" content=\"509\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ask_Scientists\" \/>\n<meta name=\"twitter:site\" content=\"@Ask_Scientists\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Todo sobre las ceramidas\",\"datePublished\":\"2023-09-26T16:00:46+00:00\",\"dateModified\":\"2023-10-17T16:18:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/\"},\"wordCount\":889,\"publisher\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AdobeStock_199906953.jpeg\",\"keywords\":[\"skin care\"],\"articleSection\":[\"Nutrition Spotlight\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/\",\"name\":\"Todo sobre las ceramidas - Ask The Scientists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AdobeStock_199906953.jpeg\",\"datePublished\":\"2023-09-26T16:00:46+00:00\",\"dateModified\":\"2023-10-17T16:18:11+00:00\",\"description\":\"Conoce uno de los componentes m\u00e1s importantes de la barrera natural de la piel que adem\u00e1s es un ingrediente clave en muchos productos para el cuidado de la piel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/#primaryimage\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AdobeStock_199906953.jpeg\",\"contentUrl\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/AdobeStock_199906953.jpeg\",\"width\":835,\"height\":509,\"caption\":\"Layers of epidermis illustration vector on white background. Medical concept.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/ceramides\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Todo sobre las ceramidas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/\",\"name\":\"Ask The Scientists\",\"description\":\"Your Source for Health and Science Information\",\"publisher\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/#organization\",\"name\":\"Ask the Scientists\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cropped-Ask-the-Scientists-DNA-Logo-No-Tail.png\",\"contentUrl\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cropped-Ask-the-Scientists-DNA-Logo-No-Tail.png\",\"width\":512,\"height\":512,\"caption\":\"Ask the Scientists\"},\"image\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AskTheScientists\",\"https:\\\/\\\/x.com\\\/Ask_Scientists\",\"https:\\\/\\\/www.instagram.com\\\/askthescientists\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWVONlSA0I4kLEd3UKpi35A\\\/featured?view_as=public\"]},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/es\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Todo sobre las ceramidas - Ask The Scientists","description":"Conoce uno de los componentes m\u00e1s importantes de la barrera natural de la piel que adem\u00e1s es un ingrediente clave en muchos productos para el cuidado de la piel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/askthescientists.com\/es\/ceramides\/","og_locale":"es_ES","og_type":"article","og_title":"Todo sobre las ceramidas - Ask The Scientists","og_description":"Conoce uno de los componentes m\u00e1s importantes de la barrera natural de la piel que adem\u00e1s es un ingrediente clave en muchos productos para el cuidado de la piel.","og_url":"https:\/\/askthescientists.com\/es\/ceramides\/","og_site_name":"Ask The Scientists","article_publisher":"https:\/\/www.facebook.com\/AskTheScientists","article_published_time":"2023-09-26T16:00:46+00:00","article_modified_time":"2023-10-17T16:18:11+00:00","og_image":[{"width":835,"height":509,"url":"https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@Ask_Scientists","twitter_site":"@Ask_Scientists","twitter_misc":{"Written by":"","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/askthescientists.com\/es\/ceramides\/#article","isPartOf":{"@id":"https:\/\/askthescientists.com\/es\/ceramides\/"},"author":{"name":"","@id":""},"headline":"Todo sobre las ceramidas","datePublished":"2023-09-26T16:00:46+00:00","dateModified":"2023-10-17T16:18:11+00:00","mainEntityOfPage":{"@id":"https:\/\/askthescientists.com\/es\/ceramides\/"},"wordCount":889,"publisher":{"@id":"https:\/\/askthescientists.com\/es\/#organization"},"image":{"@id":"https:\/\/askthescientists.com\/es\/ceramides\/#primaryimage"},"thumbnailUrl":"https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953.jpeg","keywords":["skin care"],"articleSection":["Nutrition Spotlight"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/askthescientists.com\/es\/ceramides\/","url":"https:\/\/askthescientists.com\/es\/ceramides\/","name":"Todo sobre las ceramidas - Ask The Scientists","isPartOf":{"@id":"https:\/\/askthescientists.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/askthescientists.com\/es\/ceramides\/#primaryimage"},"image":{"@id":"https:\/\/askthescientists.com\/es\/ceramides\/#primaryimage"},"thumbnailUrl":"https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953.jpeg","datePublished":"2023-09-26T16:00:46+00:00","dateModified":"2023-10-17T16:18:11+00:00","description":"Conoce uno de los componentes m\u00e1s importantes de la barrera natural de la piel que adem\u00e1s es un ingrediente clave en muchos productos para el cuidado de la piel.","breadcrumb":{"@id":"https:\/\/askthescientists.com\/es\/ceramides\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/askthescientists.com\/es\/ceramides\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/askthescientists.com\/es\/ceramides\/#primaryimage","url":"https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953.jpeg","contentUrl":"https:\/\/askthescientists.com\/wp-content\/uploads\/2023\/09\/AdobeStock_199906953.jpeg","width":835,"height":509,"caption":"Layers of epidermis illustration vector on white background. Medical concept."},{"@type":"BreadcrumbList","@id":"https:\/\/askthescientists.com\/es\/ceramides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/askthescientists.com\/es\/"},{"@type":"ListItem","position":2,"name":"Todo sobre las ceramidas"}]},{"@type":"WebSite","@id":"https:\/\/askthescientists.com\/es\/#website","url":"https:\/\/askthescientists.com\/es\/","name":"Ask The Scientists","description":"Your Source for Health and Science Information","publisher":{"@id":"https:\/\/askthescientists.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/askthescientists.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/askthescientists.com\/es\/#organization","name":"Ask the Scientists","url":"https:\/\/askthescientists.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/askthescientists.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/08\/cropped-Ask-the-Scientists-DNA-Logo-No-Tail.png","contentUrl":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/08\/cropped-Ask-the-Scientists-DNA-Logo-No-Tail.png","width":512,"height":512,"caption":"Ask the Scientists"},"image":{"@id":"https:\/\/askthescientists.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AskTheScientists","https:\/\/x.com\/Ask_Scientists","https:\/\/www.instagram.com\/askthescientists\/","https:\/\/www.youtube.com\/channel\/UCWVONlSA0I4kLEd3UKpi35A\/featured?view_as=public"]},{"@type":"Person","@id":"","url":"https:\/\/askthescientists.com\/es\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/posts\/72878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/comments?post=72878"}],"version-history":[{"count":1,"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/posts\/72878\/revisions"}],"predecessor-version":[{"id":72902,"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/posts\/72878\/revisions\/72902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/media\/72873"}],"wp:attachment":[{"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/media?parent=72878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/categories?post=72878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/askthescientists.com\/es\/wp-json\/wp\/v2\/tags?post=72878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}