{"id":19863,"date":"2017-11-06T08:30:14","date_gmt":"2017-11-06T15:30:14","guid":{"rendered":"https:\/\/askthescientists.com\/pillars-of-wellness\/"},"modified":"2022-07-25T00:14:16","modified_gmt":"2022-07-25T06:14:16","slug":"pillars-of-wellness","status":"publish","type":"post","link":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/","title":{"rendered":"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT"},"content":{"rendered":"<p><img decoding=\"async\" class=\"aligncenter size-large wp-image-13733\" src=\"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/11\/AdobeStock_163967512-1030x687.jpeg\" alt=\"holistic health and wellness\" width=\"1030\" height=\"687\" \/><\/p>\n<p>Unter Gesundheit wird oft die Abwesenheit von Krankheiten verstanden. Auch wenn diese Definition ihre Berechtigung hat, ist sie doch sehr eindimensional. Beginnen Sie also damit, Gesundheit und Wohlbefinden unter ganzheitlichen Aspekten zu betrachten. Unser pers\u00f6nliches Wohlbefinden h\u00e4ngt von weit mehr Faktoren ab als nur davon, ob wir den Winter ohne Grippe \u00fcberstehen.<\/p>\n<p>Ganzheitliche Gesundheit st\u00fctzt sich auf acht S\u00e4ulen, die k\u00f6rperliche, ern\u00e4hrungsbedingte, emotionale, soziale, spirituelle, intellektuelle, finanzielle und umfeldbezogene Aspekte umfassen.<\/p>\n<p>Diese S\u00e4ulen helfen bei der Erreichung von optimalem Wohlbefinden. Sie sind jedoch lediglich als Wegweiser zu verstehen, denn die Reise ist f\u00fcr jeden von uns einzigartig.<\/p>\n<p>Veranlagung, Pers\u00f6nlichkeit und Umfeld bestimmen dar\u00fcber, was Wohlbefinden f\u00fcr jeden einzelnen bedeutet. Daher ist ein personalisierter Ansatz wichtig. F\u00fcr alle von uns gilt jedoch: Wohlbefinden erfordert eine ganzheitliche Herangehensweise.<\/p>\n<p>Im Folgenden erfahren Sie mehr \u00fcber die einzelnen S\u00e4ulen und wie Sie sie noch besser in Ihr Leben integrieren k\u00f6nnen.<\/p>\n<h2><strong>K\u00f6rperliches Wohlbefinden<\/strong><\/h2>\n<p>Die meisten Menschen denken bei \u201ek\u00f6rperlichem Wohlbefinden\u201c an Bewegung. Regelm\u00e4\u00dfige k\u00f6rperliche Aktivit\u00e4t ist zwar ein wichtiger Aspekt, jedoch bei weitem nicht der einzige.<\/p>\n<p>Physisches Wohlbefinden erfordert n\u00e4mlich auch noch andere Dinge: Dazu geh\u00f6ren gen\u00fcgend Schlaf, die richtige Hygiene und eine gesunde Ern\u00e4hrung (mehr dar\u00fcber im n\u00e4chsten Abschnitt). Stellen Sie sich bei der Beurteilung Ihrer k\u00f6rperlichen Gesundheit folgende Fragen: Bekomme ich ausreichend Schlaf? Was steht regelm\u00e4\u00dfigem und erholsamem Schlaf entgegen?<\/p>\n<p>Forscher haben k\u00fcrzlich die Empfehlungen der National Sleep Foundation aktualisiert, nachdem eine Studie neuerlich best\u00e4tigt hatte, dass Erwachsene jede Nacht mindestens sieben bis neun Stunden schlafen sollten.<\/p>\n<p>F\u00fcr Studenten, Eltern und Workaholics ist dies oft nicht m\u00f6glich. Einfache Strategien k\u00f6nnen jedoch ein problemloses Ein- und Durchschlafen sicherstellen.<\/p>\n<p>Tipps:<\/p>\n<ul>\n<li>Schauen Sie 30\u00a0Minuten vor der Schlafenszeit nicht mehr auf den Bildschirm.<\/li>\n<li>Befolgen Sie jeden Abend eine Routine, die Sie entspannt. Dimmen Sie z.\u00a0B. das Licht, h\u00f6ren Sie beruhigende Musik und machen Sie vielleicht sogar leichte Dehn\u00fcbungen.<\/li>\n<li>Sorgen Sie f\u00fcr eine ruhige Atmosph\u00e4re ohne st\u00f6rende Ger\u00e4usche und grelles Licht. Alles, was Sie dazu brauchen, sind Verdunklungsvorh\u00e4nge und eine Maschine f\u00fcr wei\u00dfes Rauschen.<\/li>\n<\/ul>\n<h2><strong>Ern\u00e4hrungsbedingtes Wohlbefinden<\/strong><\/h2>\n<p>Die Ern\u00e4hrung ist eng mit der k\u00f6rperlichen Gesundheit verbunden. Aufgrund ihrer enormen Bedeutung bildet sie eine eigene S\u00e4ule. Welche Ern\u00e4hrung optimal ist, h\u00e4ngt vom Alter, Geschlecht, Aktivit\u00e4tsniveau und Stoffwechsel ab.<\/p>\n<p>Eine ausgewogene Ern\u00e4hrung besteht aus Nahrungsmitteln, die den K\u00f6rper mit allen lebenswichtigen N\u00e4hrstoffen versorgen. Das US-Landwirtschaftsministerium empfiehlt f\u00fcr Erwachsene eine Kost, die sich zur H\u00e4lfte aus Obst und Gem\u00fcse zusammensetzt. Die andere H\u00e4lfte sollte vor allem aus Getreide, einer kleinen Portion proteinhaltiger Produkte und einem Milcherzeugnis als Beilage bestehen.<\/p>\n<p>Indem Sie von jeder Nahrungsgruppe die geeignete Menge aufnehmen, stellen Sie sicher, dass Sie die ben\u00f6tigten Makron\u00e4hrstoffe zu sich nehmen, die Ihnen jeden Tag Energie geben. Au\u00dferdem tragen Sie dadurch zum Wachstum und zur Erholung Ihrer Muskeln bei und halten andere Abl\u00e4ufe im K\u00f6rper in Gang.<\/p>\n<p>Laut Angaben der US-Beh\u00f6rde f\u00fcr Krankheits- bzw. Seuchenkontrolle und -vorbeugung aus dem Jahr 2013 konsumieren landesweit 76\u00a0% der Erwachsenen nicht die angeratene Obstmenge pro Tag. Ein noch gr\u00f6\u00dferer Anteil\u00a0\u2013 87\u00a0%\u00a0\u2013 hielt sich nicht an die Vorgaben f\u00fcr den Verzehr von Gem\u00fcse. Wenn es sich als schwierig erweist, t\u00e4glich die empfohlenen f\u00fcnf Portionen Obst und Gem\u00fcse zu sich zu nehmen, k\u00f6nnen Erg\u00e4nzungsmittel den K\u00f6rper mit den erforderlichen N\u00e4hrstoffen versorgen.<\/p>\n<p>Die St\u00e4rkung dieser S\u00e4ule setzt voraus, dass Sie Ihre Ern\u00e4hrung genau im Blick behalten und geeignete Erg\u00e4nzungsprodukte verwenden. Stress und Zeitmangel k\u00f6nnen dies erschweren. Eine bessere Ern\u00e4hrung wirkt sich jedoch auch auf die anderen sieben S\u00e4ulen f\u00fcr Wohlbefinden positiv aus.<\/p>\n<p>Tipps:<\/p>\n<ul>\n<li>Verzehren Sie Obst und Gem\u00fcse in verschiedenen Farben, um sicherzustellen, dass Sie eine breite Palette an Mikron\u00e4hrstoffen aufnehmen.<\/li>\n<li>Achten Sie darauf, wie viel Sie essen, um Ihr Gewicht zu halten und die MyPlate-Richtlinien zu befolgen.<\/li>\n<li>Ersetzen Sie verarbeitetes Getreide durch Vollkorn, um eine ausreichende Versorgung mit Ballaststoffen zu gew\u00e4hrleisten.<\/li>\n<\/ul>\n<h2><strong>Emotionales Wohlbefinden<\/strong><\/h2>\n<p>Emotionales Wohlbefinden basiert auf der F\u00e4higkeit, angemessen mit Ihren Gef\u00fchlen umzugehen. Dazu geh\u00f6rt, diese wahrzunehmen, einzuordnen und anderen gegen\u00fcber zum Ausdruck zu bringen.<\/p>\n<p>Warum ist das wichtig? Das Leben hat H\u00f6hen und Tiefen, die sich wie eine emotionale Achterbahnfahrt anf\u00fchlen k\u00f6nnen. Je besser Sie Ihre Gef\u00fchle verstehen, verarbeiten und steuern, umso weniger holprig ist der Weg.<\/p>\n<p>Tipps:<\/p>\n<ul>\n<li>Erstellen Sie eine Liste mit den Personen, auf deren Unterst\u00fctzung Sie sich verlassen k\u00f6nnen, und notieren Sie jeweils die beste Kontaktmethode. Wenn Sie Beistand ben\u00f6tigen, kann es schwer sein, darum zu bitten. Haben Sie eine Namensliste zur Hand, wird Ihnen dieser Schritt viel leichter fallen.<\/li>\n<li>Suchen Sie sich einen Therapeuten oder Berater. Qualifizierte Unterst\u00fctzung erweist sich in schwierigen Situationen oftmals als gro\u00dfe Hilfe.<\/li>\n<li>Tagebuch zu f\u00fchren, ist eine einfache Methode, Ihre Gef\u00fchle wahrzunehmen und zu verarbeiten, insbesondere, wenn Sie nicht dar\u00fcber sprechen m\u00f6chten. Es ist hervorragend geeignet, um Ihren Fortschritt und Ihr Wachstum im Blick zu behalten.<\/li>\n<\/ul>\n<h2><strong>Soziales Wohlbefinden<\/strong><\/h2>\n<p>F\u00fcr soziales Wohlbefinden sind gute Beziehungen zu anderen Menschen wichtig. Dazu geh\u00f6rt auch, mit Konflikten umgehen zu k\u00f6nnen.<\/p>\n<p>Soziale Beziehungen schaffen Unterst\u00fctzungssysteme, auf die Sie in schwierigen Zeiten zur\u00fcckgreifen k\u00f6nnen. Im Rahmen einer Studie der Harvard-Universit\u00e4t mit mehreren Hundert Teilnehmern wurden 80\u00a0Jahre lang Daten zur Entwicklung im Erwachsenenalter gesammelt. Eine k\u00fcrzlich durchgef\u00fchrte Untersuchung mit einem Teil dieser Gruppe, die aus 80- bis 89-J\u00e4hrigen bestand, ging dem Zusammenhang zwischen Zufriedenheit in der Ehe, gesellschaftlichem Leben und Gl\u00fcck auf den Grund. Die Forscher fanden heraus, dass Menschen, die viel Zeit mit anderen verbringen, mehr Freude am Leben haben.<\/p>\n<p>Indem wir uns mit Personen umgeben, denen wir etwas bedeuten, k\u00f6nnen wir unser Wohlbefinden erheblich steigern. Wenn uns das Leben vor Probleme und Herausforderungen stellt, brauchen wir jemanden, der uns unterst\u00fctzt und versteht. Der Aufbau und die Pflege dieser Netzwerke erfordern Zeit und Energie, lohnt sich jedoch auf lange Sicht.<\/p>\n<p>Tipps:<\/p>\n<ul>\n<li>Kn\u00fcpfen Sie neue Bekanntschaften \u00fcber soziale Netzwerke, bei gesellschaftlichen Veranstaltungen oder beim Freiwilligendienst kennen.<\/li>\n<li>Planen Sie regelm\u00e4\u00dfig etwas Zeit ein, um den Kontakt zu weiter entfernt lebenden Freunden und Verwandten zu pflegen. Machen Sie es sich zur Gewohnheit, jede Woche mit Familienmitgliedern und Personen aus Ihrem Bekanntenkreis zu kommunizieren.<\/li>\n<li>Dies kann per Telefon, E-Mail oder Brief erfolgen. Besonders ein handschriftlicher Briefwechsel kann eine sehr enge Verbindung schaffen.<\/li>\n<\/ul>\n<h2><strong>Spirituelles Wohlbefinden<\/strong><\/h2>\n<p>Diese S\u00e4ule sieht f\u00fcr jeden anders aus, da Spiritualit\u00e4t eine ganz pers\u00f6nliche Komponente des allgemeinen Wohlbefindens ist. In dem Leben verschiedener Menschen spielt sie eine unterschiedlich gro\u00dfe Rolle, je nachdem, wie eine Person diesen Aspekt definiert.<\/p>\n<p>Spiritualit\u00e4t wird \u00fcblicherweise als eine innere Haltung beschrieben, die dem Leben einen Sinn gibt, als moralischer Kompass dient und so f\u00fcr ein emotionales Gleichgewicht sorgt. Viele kultivieren ihre Spiritualit\u00e4t durch Meditation, Beten oder andere Aktivit\u00e4ten, die eine Verbindung zur Natur oder zu einer h\u00f6heren Macht herstellen.<\/p>\n<p>Jeder k\u00fcmmert sich auf seine Weise um die Aufrechterhaltung seines spirituellen Wohlbefindens. Es geht nicht um eine bestimmte Religion oder irgendein Glaubenssystem. Bei der spirituellen Gesundheit steht Ihre Reise zu sich selbst im Mittelpunkt. Manche Menschen praktizieren Achtsamkeit, um sich \u00fcber ihre Absichten klar zu werden und sich von Werten leiten zu lassen, die ihnen wichtig sind. Was Sie f\u00fcr Ihre spirituelle Gesundheit tun, liegt ganz bei Ihnen.<\/p>\n<p>Tipps:<\/p>\n<ul>\n<li>Nehmen Sie sich jeden Tag etwas Zeit f\u00fcr sich\u00a0\u2013 frei von Ablenkungen, St\u00f6rungen und gr\u00f6\u00dferen Aktivit\u00e4ten. Diese Unterbrechung kann zum Entspannen, Nachdenken, Meditieren oder Beten genutzt werden.<\/li>\n<li>F\u00fchren Sie ein Tagebuch. Es kann helfen, einen klaren Kopf zu bekommen und Ihre Ziele zu erreichen.<\/li>\n<li>Denken Sie dar\u00fcber nach, welche drei Werte in Ihrem Leben am wichtigsten sind, schreiben Sie sie auf und rufen Sie sie sich immer wieder in Erinnerung. Auf diese Weise wird es Ihnen leichter fallen, im Alltag Entscheidungen zu treffen\u00a0\u2013 gro\u00dfe und kleine. Sie werden merken, dass es Ihnen bald keine Schwierigkeiten mehr bereiten wird, \u201eJa\u201c zu sagen zu Dingen, die Ihnen etwas bedeuten, und \u201eNein\u201c zu allem, was nicht mit Ihren Werten in Einklang steht.<\/li>\n<\/ul>\n<h2><strong>Intellektuelles Wohlbefinden<\/strong><\/h2>\n<p>Das intellektuelle Wohlbefinden wird durch geistige Bet\u00e4tigung gef\u00f6rdert. Eignen Sie sich neue F\u00e4higkeiten und Kenntnisse an, die Sie inspirieren, herausfordern und weiterbringen. Sie k\u00f6nnen Ihren Verstand auf verschiedene Art fordern\u00a0\u2013 je nachdem, worauf Sie gerade Lust haben. Versuchen Sie es z.\u00a0B. mit Denkspielen, Puzzles oder Lernaufgaben. Auch Gespr\u00e4che k\u00f6nnen intellektuell stimulierend sein.<\/p>\n<p>Manche Menschen begeben sich zudem auf eine Reise zur Selbstfindung und pers\u00f6nlichen Weiterentwicklung. Die Nutzung von Fortbildungsm\u00f6glichkeiten, die Beteiligung an gemeinn\u00fctzigen Aktivit\u00e4ten und \u00e4hnliches sind nur einige der Dinge, die Sie ausprobieren k\u00f6nnen.<\/p>\n<p>Tipps:<\/p>\n<ul>\n<li>Halten Sie Ausschau nach Weiterbildungsangeboten der Hochschule vor Ort.<\/li>\n<li>Treten Sie einem Buchklub bei oder melden Sie sich bei einer Bibliothek an.<\/li>\n<li>Fangen Sie an, ein Tagebuch zu f\u00fchren, oder reflektieren Sie auf andere Weise \u00fcber sich selbst.<\/li>\n<\/ul>\n<h2><strong>Finanzielles Wohlbefinden<\/strong><\/h2>\n<p>F\u00fcr finanzielles Wohlbefinden ist es wichtig, nicht \u00fcber seine Verh\u00e4ltnisse zu leben und angemessen f\u00fcr die Zukunft vorzusorgen. Dies ist nicht immer einfach, langfristig zahlen sich jedoch auch noch so kleine Schritte aus.<\/p>\n<p>Das Thema finanzielles Wohlbefinden mag zun\u00e4chst langweilig erscheinen. Verbesserungen in diesem Bereich sind jedoch Garant f\u00fcr eine St\u00e4rkung der \u00fcbrigen S\u00e4ulen ganzheitlicher Gesundheit. F\u00fcr US-Amerikaner z\u00e4hlen finanzielle Probleme immerhin zu den gr\u00f6\u00dften Stressfaktoren. Kleine Schritte mit dem Ziel, Ihre Ausgaben unter Kontrolle zu bekommen, k\u00f6nnen eine enorme Entlastung bewirken.<\/p>\n<p>Tipps:<\/p>\n<ul>\n<li>Ganz oben auf Ihrer Priorit\u00e4tenliste sollte die R\u00fcckzahlung von Schulden stehen.<\/li>\n<li>Erstellen Sie mit Hilfe eines Online-Systems wie Mint oder gemeinsam mit einem pers\u00f6nlichen Finanzplaner ein Budget.<\/li>\n<li>Planen Sie jeden Monat einen festen Betrag f\u00fcr nicht lebensnotwendige Dinge wie Unterhaltung, Ausgehen und Erholung ein.<\/li>\n<\/ul>\n<h2><strong>Umfeldbezogenes Wohlbefinden<\/strong><\/h2>\n<p>Diese Art des Wohlbefindens ist eng verkn\u00fcpft mit dem unmittelbaren pers\u00f6nlichen Umfeld und der Gesellschaft, in dem bzw. der Sie leben und arbeiten. Mit anderen Worten: Es ist von der Beziehung zwischen Ihnen und Ihrem n\u00e4heren und entfernteren Umfeld abh\u00e4ngig. Was tun Sie, um Ihr Umfeld zu unterst\u00fctzen? Und inwiefern wirkt sich Ihr Umfeld positiv auf Ihre Gesundheit, Ihr Wohlbefinden und Ihre Sicherheit aus?<\/p>\n<p>Wenn Sie Ihr umfeldbezogenes Wohlbefinden st\u00e4rken, werden auch Ihre Mitmenschen dies sp\u00fcren. Je mehr Sie sich um Ihr Umfeld k\u00fcmmern und es respektieren, desto mehr Halt wird es Ihnen in Ihrem t\u00e4glichen Leben bieten. Dabei k\u00f6nnen Sie auf verschiedenen Ebenen aktiv werden, z.\u00a0B. am Arbeitsplatz und in der Nachbarschaft.<\/p>\n<p>Tipps:<\/p>\n<ul>\n<li>Am Arbeitsplatz: Sorgen Sie daf\u00fcr, dass Ihr Schreibtisch stets aufger\u00e4umt ist. Dies regt die Kreativit\u00e4t und Produktivit\u00e4t an.<\/li>\n<li>In der Nachbarschaft: Beteiligen Sie sich an S\u00e4uberungsaktionen in Ihrem Stadtteil. Dazu kann geh\u00f6ren, weniger M\u00fcll zu produzieren, nicht mehr ben\u00f6tigte Dinge zu recyceln und Abfall in Ihrem Viertel einzusammeln.<\/li>\n<li>Allgemein: Fahren Sie seltener mit dem Auto. Egal, ob Sie die Anzahl der Fahrten reduzieren, indem Sie mehrere Erledigungen kombinieren oder das Auto ganz stehenlassen: Viele kleine Bem\u00fchungen machen zusammen einen gro\u00dfen Unterschied.<\/li>\n<\/ul>\n<h2><strong>Wie Sie Ihr Wohlbefinden steigern k\u00f6nnen<\/strong><\/h2>\n<p>Wohlbefinden hat f\u00fcr jeden von uns eine andere Bedeutung. Letztendlich erm\u00f6glicht es uns, pers\u00f6nliche Ziele zu erreichen. Wer auf ganzheitliche Weise f\u00fcr das Wohl von K\u00f6rper, Geist und Seele sorgt, dem f\u00e4llt es leichter, ein zufriedenes Leben zu f\u00fchren.<\/p>\n<p>Bevor Sie sich auf Ihren pers\u00f6nlichen Weg zu optimalem Wohlbefinden begeben, sollten Sie sich n\u00e4her mit den acht S\u00e4ulen besch\u00e4ftigen, die wir oben vorgestellt haben. Finden Sie heraus, welche davon Ihre Aufmerksamkeit erfordern. Und denken Sie daran: Indem Sie jede einzelne S\u00e4ule st\u00e4rken, schaffen Sie ein solides Fundament f\u00fcr ein gesundes und erf\u00fclltes Leben.<\/p>\n<h2><strong>\u00dcber die Autorin<\/strong><\/h2>\n<p><a href=\"https:\/\/askthescientists.com\/de\/author\/jtempleton\/\">Jenna Templeton<\/a>\u00a0ist als Gesundheitsp\u00e4dagogin und freiberufliche Wissenschaftsautorin in Salt Lake City, Utah t\u00e4tig. Nachdem sie ihren Bachelor in Chemie an der Virginia Tech abgeschlossen hatte, arbeitete sie f\u00fcnf Jahre lang als Forscherin in der Ern\u00e4hrungsindustrie. Dort wurde ihr Interesse an einer gesunden Lebensweise geweckt, was sie dazu bewog, an der University of Utah Gesundheitsf\u00f6rderung und -p\u00e4dagogik zu studieren. In ihrer Freizeit besucht Templeton gerne Live-Konzerte und arbeitet im Garten. Au\u00dferdem begeistert sie sich f\u00fcr alles, was mit Essen zu tun hat, und f\u00e4hrt zur Erholung in die Wasatch-Berge.<\/p>\n<h2><strong>Quellen<\/strong><\/h2>\n<p><a href=\"http:\/\/www.sleephealthjournal.org\/article\/S2352-7218(15)00015-7\/pdf\">Hirshkowitz M et al. \u201cNational Sleep Foundation\u2019s sleep time duration recommendations: methodology and results summary\u201d. <em>Sleep Health 1 <\/em>(2015). 1(1): 40-43.<\/a><\/p>\n<p><a href=\"https:\/\/www.cdc.gov\/mmwr\/preview\/mmwrhtml\/mm6426a1.htm\">Moore LV and Thompson FE. \u201cAdult Fruit and Vegetable Intake Recommendations \u2013 United States, 2013\u201d. Morbidity and Mortality Weekly Report.<\/a><\/p>\n<p><a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pubmed\/20545426\">Waldinger RJ, Schulz MS. \u201cWhat\u2019s love got to do with it? Social functioning, perceived health, and daily happiness in married octogenarians\u201d. <em>Psychology and Aging<\/em> (2010). 25(2): 422-431. <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unter Gesundheit wird oft die Abwesenheit von Krankheiten verstanden. Auch wenn diese Definition ihre Berechtigung hat, ist sie doch sehr eindimensional. Beginnen Sie also damit, Gesundheit und Wohlbefinden unter ganzheitlichen Aspekten zu betrachten. Unser pers\u00f6nliches Wohlbefinden h\u00e4ngt von weit mehr Faktoren ab als nur davon, ob wir den Winter ohne Grippe \u00fcberstehen. Ganzheitliche Gesundheit st\u00fctzt [&hellip;]<\/p>\n","protected":false},"author":5186,"featured_media":13733,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[6125],"tags":[20827],"class_list":["post-19863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nutrition_spotlight-de","tag-healthy-habits-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT - Ask The Scientists<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT - Ask The Scientists\" \/>\n<meta property=\"og:description\" content=\"Unter Gesundheit wird oft die Abwesenheit von Krankheiten verstanden. Auch wenn diese Definition ihre Berechtigung hat, ist sie doch sehr eindimensional. Beginnen Sie also damit, Gesundheit und Wohlbefinden unter ganzheitlichen Aspekten zu betrachten. Unser pers\u00f6nliches Wohlbefinden h\u00e4ngt von weit mehr Faktoren ab als nur davon, ob wir den Winter ohne Grippe \u00fcberstehen. Ganzheitliche Gesundheit st\u00fctzt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/\" \/>\n<meta property=\"og:site_name\" content=\"Ask The Scientists\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AskTheScientists\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-06T15:30:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-25T06:14:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/11\/AdobeStock_163967512.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"801\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jenna Templeton\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Ask_Scientists\" \/>\n<meta name=\"twitter:site\" content=\"@Ask_Scientists\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jenna Templeton\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/\"},\"author\":{\"name\":\"Jenna Templeton\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#\\\/schema\\\/person\\\/b36c36970f96205baed843a64d2957ca\"},\"headline\":\"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT\",\"datePublished\":\"2017-11-06T15:30:14+00:00\",\"dateModified\":\"2022-07-25T06:14:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/\"},\"wordCount\":2174,\"publisher\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AdobeStock_163967512.jpeg\",\"keywords\":[\"healthy habits\"],\"articleSection\":[\"Nutrition Spotlight\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/\",\"name\":\"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT - Ask The Scientists\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AdobeStock_163967512.jpeg\",\"datePublished\":\"2017-11-06T15:30:14+00:00\",\"dateModified\":\"2022-07-25T06:14:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/#primaryimage\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AdobeStock_163967512.jpeg\",\"contentUrl\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/AdobeStock_163967512.jpeg\",\"width\":1200,\"height\":801,\"caption\":\"holistic health and wellness\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/pillars-of-wellness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/\",\"name\":\"Ask The Scientists\",\"description\":\"Your Source for Health and Science Information\",\"publisher\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#organization\",\"name\":\"Ask the Scientists\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cropped-Ask-the-Scientists-DNA-Logo-No-Tail.png\",\"contentUrl\":\"https:\\\/\\\/askthescientists.com\\\/wp-content\\\/uploads\\\/2017\\\/08\\\/cropped-Ask-the-Scientists-DNA-Logo-No-Tail.png\",\"width\":512,\"height\":512,\"caption\":\"Ask the Scientists\"},\"image\":{\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/AskTheScientists\",\"https:\\\/\\\/x.com\\\/Ask_Scientists\",\"https:\\\/\\\/www.instagram.com\\\/askthescientists\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCWVONlSA0I4kLEd3UKpi35A\\\/featured?view_as=public\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/#\\\/schema\\\/person\\\/b36c36970f96205baed843a64d2957ca\",\"name\":\"Jenna Templeton\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e1aed683b0ae3a9e64ef021b69835b927422753f235ba1ea97a3f7c5de2e22?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e1aed683b0ae3a9e64ef021b69835b927422753f235ba1ea97a3f7c5de2e22?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/32e1aed683b0ae3a9e64ef021b69835b927422753f235ba1ea97a3f7c5de2e22?s=96&d=mm&r=g\",\"caption\":\"Jenna Templeton\"},\"description\":\"Jenna Templeton is a health educator and freelance science writer living in Salt Lake City, Utah. After receiving a bachelor of science degree in chemistry from Virginia Tech, Jenna spent five years as a research scientist in the nutritional industry. This work fueled her interest in personal wellness, leading her to pursue a graduate degree in Health Promotion &amp; Education from the University of Utah. Outside of work, Jenna enjoys live music, gardening, all things food, and playing in the Wasatch mountains.\",\"url\":\"https:\\\/\\\/askthescientists.com\\\/de\\\/author\\\/jtempleton\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT - Ask The Scientists","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/","og_locale":"de_DE","og_type":"article","og_title":"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT - Ask The Scientists","og_description":"Unter Gesundheit wird oft die Abwesenheit von Krankheiten verstanden. Auch wenn diese Definition ihre Berechtigung hat, ist sie doch sehr eindimensional. Beginnen Sie also damit, Gesundheit und Wohlbefinden unter ganzheitlichen Aspekten zu betrachten. Unser pers\u00f6nliches Wohlbefinden h\u00e4ngt von weit mehr Faktoren ab als nur davon, ob wir den Winter ohne Grippe \u00fcberstehen. Ganzheitliche Gesundheit st\u00fctzt [&hellip;]","og_url":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/","og_site_name":"Ask The Scientists","article_publisher":"https:\/\/www.facebook.com\/AskTheScientists","article_published_time":"2017-11-06T15:30:14+00:00","article_modified_time":"2022-07-25T06:14:16+00:00","og_image":[{"width":1200,"height":801,"url":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/11\/AdobeStock_163967512.jpeg","type":"image\/jpeg"}],"author":"Jenna Templeton","twitter_card":"summary_large_image","twitter_creator":"@Ask_Scientists","twitter_site":"@Ask_Scientists","twitter_misc":{"Verfasst von":"Jenna Templeton","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/#article","isPartOf":{"@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/"},"author":{"name":"Jenna Templeton","@id":"https:\/\/askthescientists.com\/de\/#\/schema\/person\/b36c36970f96205baed843a64d2957ca"},"headline":"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT","datePublished":"2017-11-06T15:30:14+00:00","dateModified":"2022-07-25T06:14:16+00:00","mainEntityOfPage":{"@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/"},"wordCount":2174,"publisher":{"@id":"https:\/\/askthescientists.com\/de\/#organization"},"image":{"@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/#primaryimage"},"thumbnailUrl":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/11\/AdobeStock_163967512.jpeg","keywords":["healthy habits"],"articleSection":["Nutrition Spotlight"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/","url":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/","name":"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT - Ask The Scientists","isPartOf":{"@id":"https:\/\/askthescientists.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/#primaryimage"},"image":{"@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/#primaryimage"},"thumbnailUrl":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/11\/AdobeStock_163967512.jpeg","datePublished":"2017-11-06T15:30:14+00:00","dateModified":"2022-07-25T06:14:16+00:00","breadcrumb":{"@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/askthescientists.com\/de\/pillars-of-wellness\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/#primaryimage","url":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/11\/AdobeStock_163967512.jpeg","contentUrl":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/11\/AdobeStock_163967512.jpeg","width":1200,"height":801,"caption":"holistic health and wellness"},{"@type":"BreadcrumbList","@id":"https:\/\/askthescientists.com\/de\/pillars-of-wellness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/askthescientists.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"DIE ACHT S\u00c4ULEN GANZHEITLICHER GESUNDHEIT"}]},{"@type":"WebSite","@id":"https:\/\/askthescientists.com\/de\/#website","url":"https:\/\/askthescientists.com\/de\/","name":"Ask The Scientists","description":"Your Source for Health and Science Information","publisher":{"@id":"https:\/\/askthescientists.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/askthescientists.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/askthescientists.com\/de\/#organization","name":"Ask the Scientists","url":"https:\/\/askthescientists.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/askthescientists.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/08\/cropped-Ask-the-Scientists-DNA-Logo-No-Tail.png","contentUrl":"https:\/\/askthescientists.com\/wp-content\/uploads\/2017\/08\/cropped-Ask-the-Scientists-DNA-Logo-No-Tail.png","width":512,"height":512,"caption":"Ask the Scientists"},"image":{"@id":"https:\/\/askthescientists.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/AskTheScientists","https:\/\/x.com\/Ask_Scientists","https:\/\/www.instagram.com\/askthescientists\/","https:\/\/www.youtube.com\/channel\/UCWVONlSA0I4kLEd3UKpi35A\/featured?view_as=public"]},{"@type":"Person","@id":"https:\/\/askthescientists.com\/de\/#\/schema\/person\/b36c36970f96205baed843a64d2957ca","name":"Jenna Templeton","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/32e1aed683b0ae3a9e64ef021b69835b927422753f235ba1ea97a3f7c5de2e22?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/32e1aed683b0ae3a9e64ef021b69835b927422753f235ba1ea97a3f7c5de2e22?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/32e1aed683b0ae3a9e64ef021b69835b927422753f235ba1ea97a3f7c5de2e22?s=96&d=mm&r=g","caption":"Jenna Templeton"},"description":"Jenna Templeton is a health educator and freelance science writer living in Salt Lake City, Utah. After receiving a bachelor of science degree in chemistry from Virginia Tech, Jenna spent five years as a research scientist in the nutritional industry. This work fueled her interest in personal wellness, leading her to pursue a graduate degree in Health Promotion &amp; Education from the University of Utah. Outside of work, Jenna enjoys live music, gardening, all things food, and playing in the Wasatch mountains.","url":"https:\/\/askthescientists.com\/de\/author\/jtempleton\/"}]}},"_links":{"self":[{"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/posts\/19863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/users\/5186"}],"replies":[{"embeddable":true,"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/comments?post=19863"}],"version-history":[{"count":0,"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/posts\/19863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/media\/13733"}],"wp:attachment":[{"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/media?parent=19863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/categories?post=19863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/askthescientists.com\/de\/wp-json\/wp\/v2\/tags?post=19863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}